{"id":5956,"date":"2021-11-25T18:09:22","date_gmt":"2021-11-25T18:09:22","guid":{"rendered":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/producto\/yee-pvc-sanit-cem-4\/"},"modified":"2024-07-11T19:29:12","modified_gmt":"2024-07-11T19:29:12","slug":"yee-pvc-sanit-cem-4","status":"publish","type":"product","link":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/producto\/yee-pvc-sanit-cem-4\/","title":{"rendered":"YEE PVC SANITARIO DE NORMA 4&#8243;"},"content":{"rendered":"<p><strong>YEE PVC SANITARIO DE NORMA 4&#8243;<\/strong><br \/>\nYee sanitaria de pvc de norma de 110mm es ideal para sistemas sanitarios para desahogar por gravedad aguas residuales dom\u00e9sticas o industriales, aguas pluviales en edificios y sistemas de ventilaci\u00f3n, fabricado de resina virgen y tres salidas de 110 mm.<br \/>\n<strong>Especificaciones t\u00e9cnicas<\/strong><br \/>\n\u2022 Usos: Conducci\u00f3n de aguas residuales<br \/>\n\u2022 Color: Blanco<br \/>\n\u2022 Di\u00e1metro: 4&#8243;<br \/>\n\u2022 Material: PVC<br \/>\n\u2022 Tipo: Sanitario<br \/>\n\u2022 Ancho: 115 mm<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>YEE PVC SANITARIO DE NORMA 4&#8243;<\/strong><br \/>\nYee sanitaria de pvc de norma de 110mm es ideal para sistemas sanitarios para desahogar por gravedad aguas residuales dom\u00e9sticas o industriales, aguas pluviales en edificios y sistemas de ventilaci\u00f3n, fabricado de resina virgen y tres salidas de 110 mm.<\/p>\n","protected":false},"featured_media":7470,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[670,645],"product_tag":[],"class_list":{"0":"post-5956","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sanitario","7":"product_cat-yee","9":"first","10":"instock","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/product\/5956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/comments?post=5956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/media\/7470"}],"wp:attachment":[{"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/media?parent=5956"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/product_brand?post=5956"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/product_cat?post=5956"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/product_tag?post=5956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}