{"id":1858,"date":"2021-11-25T17:49:37","date_gmt":"2021-11-25T17:49:37","guid":{"rendered":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/producto\/cemento-blanco-fortaleza\/"},"modified":"2023-10-23T19:17:02","modified_gmt":"2023-10-23T19:17:02","slug":"cemento-blanco-fortaleza","status":"publish","type":"product","link":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/producto\/cemento-blanco-fortaleza\/","title":{"rendered":"CEMENTO BLANCO FORTALEZA"},"content":{"rendered":"<p><strong>CEMENTO BLANCO FORTALEZA.<\/strong><br \/>\nEl Cemento Portland Ordinario clase resistente 30, resistencia r\u00e1pida, blanco como caracter\u00edstica especial (CPO 30 RB), es ideal para construir elementos estructurales y\/o arquitect\u00f3nicos donde se requiera mayor blancura.<br \/>\nAPLICACIONES:<br \/>\nEl Cemento Fortaleza CPO 30 RB, adem\u00e1s de ser empleado para elaborar concretos estructurales, es ideal para obras ornamentales donde las exigencias est\u00e9ticas son mayores:<br \/>\n\u2022 Vivienda en general<br \/>\n\u2022 Concretos coloreados<br \/>\n\u2022 Acabados arquitect\u00f3nicos<br \/>\n\u2022 Prefabricaci\u00f3n de lavaderos, l\u00e1pidas, losas,mosaicos, etc.<br \/>\n\u2022 Fabricaci\u00f3n de adhesivos cer\u00e1micos,pegazulejos, boquillas, etc.<br \/>\n\u2022 Estucos, etc.<br \/>\nCARACTERISTICAS FISICAS:<br \/>\nCumple ampliamente con las especificaciones de calidad establecidas en la norma mexicana del cemento NMX-C-414-ONNCCE vigente.<br \/>\nBlancura:<br \/>\n\u2022 M\u00ednimo 70 %<br \/>\nResistencia a compresi\u00f3n:<br \/>\n\u2022 M\u00ednima a 3 d\u00edas: 20 N\/mm\u00b2 (204 kg\/cm\u00b2),<br \/>\n\u2022 M\u00ednima a 28 d\u00edas: 30 N7mm\u00b2 (306 kg\/cm\u00b2)<br \/>\nTiempo de fraguado:<br \/>\n\u2022 Inicial: 45 minutos (m\u00ednimo)<br \/>\n\u2022 Final: 600 minutos (m\u00e1ximo)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CEMENTO BLANCO FORTALEZA.<br \/>\nEl Cemento Portland Ordinario clase resistente 30, resistencia r\u00e1pida, blanco como caracter\u00edstica especial (CPO 30 RB), es ideal para construir elementos estructurales y\/o arquitect\u00f3nicos donde se requiera mayor blancura.<\/p>\n","protected":false},"featured_media":6487,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[155],"product_tag":[],"class_list":{"0":"post-1858","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cemento","8":"first","9":"instock","10":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/product\/1858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/comments?post=1858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/media\/6487"}],"wp:attachment":[{"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/media?parent=1858"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/product_brand?post=1858"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/product_cat?post=1858"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.necsamx.com\/TiendadeMaterialElectrico\/wp-json\/wp\/v2\/product_tag?post=1858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}